{"id":4,"count":44,"description":"","link":"https:\/\/planetmacneil.org\/blog\/category\/publications\/art-culture-politics\/","name":"Art, Culture (and Politics)","slug":"art-culture-politics","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/planetmacneil.org\/blog\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planetmacneil.org\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/planetmacneil.org\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/planetmacneil.org\/blog\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/planetmacneil.org\/blog\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}